{"id":12399,"date":"2022-07-24T05:02:42","date_gmt":"2022-07-24T05:02:42","guid":{"rendered":"https:\/\/appsaf.apieproject.com\/news\/?p=12399"},"modified":"2022-07-24T05:02:43","modified_gmt":"2022-07-24T05:02:43","slug":"linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale","status":"publish","type":"post","link":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/","title":{"rendered":"L&rsquo;Institut Cervantes \u00e9tudie l&rsquo;ouverture d&rsquo;un Observatoire espagnol pour l&rsquo;Afrique subsaharienne en Guin\u00e9e \u00e9quatoriale"},"content":{"rendered":"<p>Le directeur de l&rsquo;Institut Cervantes, Luis Garc\u00eda Montero, a inaugur\u00e9 la Tribune de l&rsquo;hispanisme \u00e9quatoguin\u00e9en \u00e0 Malabo, un forum de dialogue avec les hispanistes du pays africain, une r\u00e9gion o\u00f9 \u00ab\u00a0l&rsquo;Observatoire de l&rsquo;espagnol pour l&rsquo;Afrique subsaharienne &#8211; un projet \u00e0 l&rsquo;\u00e9tude &#8211; a sa place naturelle\u00a0\u00bb, a d\u00e9clar\u00e9 le directeur. Le directeur a \u00e9galement tenu une r\u00e9union avec des repr\u00e9sentants du minist\u00e8re des Affaires \u00e9trang\u00e8res et a particip\u00e9 \u00e0 une session de l&rsquo;Acad\u00e9mie \u00e9quatoguin\u00e9enne de la langue espagnole (AEGLE), o\u00f9 il a rencontr\u00e9 son pr\u00e9sident et donn\u00e9 une conf\u00e9rence intitul\u00e9e \u00ab\u00a0L&rsquo;avenir de l&rsquo;espagnol dans le monde\u00a0\u00bb.<\/p>\n<p>L&rsquo;agenda institutionnel du directeur de Cervantes a commenc\u00e9 par une r\u00e9union avec le secr\u00e9taire g\u00e9n\u00e9ral des affaires \u00e9trang\u00e8res et de la coop\u00e9ration internationale de Guin\u00e9e \u00e9quatoriale, Mat\u00edas Nguema Mba Medja, et avec la directrice g\u00e9n\u00e9rale pour l&rsquo;Europe et l&rsquo;Am\u00e9rique, Josefina Nguema Ayaga. Le secr\u00e9taire a soulign\u00e9 que \u00ab\u00a0la Guin\u00e9e est la patrie des Espagnols en Afrique et repr\u00e9sente fi\u00e8rement l&rsquo;espagnol sur le continent\u00a0\u00bb, raison pour laquelle il s&rsquo;est dit \u00ab\u00a0tr\u00e8s reconnaissant que la Guin\u00e9e \u00e9quatoriale ait \u00e9t\u00e9 choisie pour cet Observatoire\u00a0\u00bb.<\/p>\n<p>En outre, le directeur de l&rsquo;Institut Cervantes rencontrera le premier vice-premier ministre, charg\u00e9 du minist\u00e8re de l&rsquo;\u00c9ducation, de l&rsquo;enseignement universitaire et des sports, Clemente Engonga Nguema Onguene, et le recteur de l&rsquo;Universit\u00e9 nationale de Guin\u00e9e \u00e9quatoriale (UNGE), Filiberto Ntututmu Nguema, ainsi que plusieurs \u00e9crivains \u00e9quatoguin\u00e9ens.<\/p>\n<p>Forum pour la rencontre et la reconnaissance de l&rsquo;espagnol en Afrique<br \/>\nLe directeur de l&rsquo;Institut Cervantes a d\u00e9fini la Tribuna del Hispanismo Ecuatoguineano, qui se tient au Centre culturel espagnol de la capitale \u00e9quatoguin\u00e9enne, comme \u00ab\u00a0une opportunit\u00e9 exceptionnelle qui reconna\u00eet la valeur de la Guin\u00e9e \u00e9quatoriale en tant que seul pays africain dont l&rsquo;espagnol est la langue maternelle\u00a0\u00bb.<\/p>\n<p>Le pr\u00e9sident d&rsquo;AEGLE, Agust\u00edn Nze Nfumu, a exprim\u00e9 sa joie de \u00ab\u00a0participer \u00e0 un acte d\u00e9terminant de la belle et riche langue qui nous unit, au-del\u00e0 des couleurs et des consid\u00e9rations p\u00e9rissables\u00a0\u00bb. Il a \u00e9galement soulign\u00e9 que \u00ab\u00a0l&rsquo;espagnol en Guin\u00e9e \u00e9quatoriale n&rsquo;est pas une langue, c&rsquo;est la langue\u00a0\u00bb et que \u00ab\u00a0malgr\u00e9 la menace linguistique que repr\u00e9sentent l&rsquo;anglais ou le fran\u00e7ais, nous sommes d\u00e9termin\u00e9s \u00e0 faire en sorte que notre langue se d\u00e9veloppe toujours plus vigoureusement\u00a0\u00bb.<\/p>\n<p>L&rsquo;ambassadeur d&rsquo;Espagne en Guin\u00e9e \u00e9quatoriale, Alfonso Barnuevo Sebasti\u00e1n de Erice, a \u00e9galement particip\u00e9 \u00e0 l&rsquo;inauguration de ce forum, le deuxi\u00e8me \u00e0 se tenir hors d&rsquo;Espagne &#8211; apr\u00e8s celui de Dakar en 2020. Le diplomate a rappel\u00e9 comment, lors du premier congr\u00e8s international de culture hispano-africaine, qui s&rsquo;est tenu \u00e0 Bata (Guin\u00e9e \u00e9quatoriale) en 1984, \u00ab\u00a0le concept d&rsquo;afro-ib\u00e9ro-am\u00e9ricanisme a \u00e9t\u00e9 lanc\u00e9 avec enthousiasme et conviction\u00a0\u00bb, dans une validit\u00e9 permanente o\u00f9 \u00ab\u00a0la langue espagnole n&rsquo;est plus la langue de l&rsquo;Espagne, comme elle est la langue de l&rsquo;Equatoguin\u00e9en, du Mexicain ou de l&rsquo;Uruguayen\u00a0\u00bb.<\/p>\n<p>En ce qui concerne la cr\u00e9ation d&rsquo;un Observatoire de l&rsquo;espagnol pour l&rsquo;Afrique subsaharienne, Garc\u00eda Montero a soulign\u00e9 l&rsquo;importance de sa mise en place \u00a0\u00bb pour \u00e9tudier et soutenir la consolidation en Afrique d&rsquo;une langue qui repr\u00e9sente aujourd&rsquo;hui un horizon d&rsquo;opportunit\u00e9s tr\u00e8s importantes dans la mondialisation et le dialogue culturel international \u00ab\u00a0. Dans ce sens, il a avanc\u00e9 que l&rsquo;institution travaille en collaboration avec l&rsquo;Universit\u00e9 Complutense &#8211; et les relations de cette derni\u00e8re avec les universit\u00e9s de Guin\u00e9e \u00e9quatoriale &#8211; et consid\u00e9rerait comme \u00a0\u00bb tr\u00e8s naturel de commencer ce projet dans un pays qui a l&rsquo;espagnol comme langue et qui a tant lutt\u00e9 pour son importance \u00ab\u00a0.<\/p>\n<p>L&rsquo;espagnol en Afrique sub-saharienne<br \/>\nLa table ronde, anim\u00e9e par la directrice acad\u00e9mique de l&rsquo;Institut Cervantes, Carmen Pastor Villalba, a vu la participation des sp\u00e9cialistes Juan Bautista Osubita, universitaire et directeur de l&rsquo;antenne r\u00e9gionale de l&rsquo;AEGLE ; Filomena Avomo Esono, directrice de la direction de l&rsquo;information de l&rsquo;Universit\u00e9 nationale de Guin\u00e9e \u00e9quatoriale ; Jos\u00e9 Fernando Siale Djangany, juriste et \u00e9crivain, universitaire de l&rsquo;AEGLE et collaborateur du Centre d&rsquo;\u00e9tudes afro-hispaniques de l&rsquo;Universit\u00e9 nationale d&rsquo;enseignement \u00e0 distance (UNED) et Mikel Larre Mu\u00f1oz, professeur de la Facult\u00e9 des sciences humaines et collaborateur de l&rsquo;AEGLE dans la ville de Bata.<\/p>\n<p>Organis\u00e9 par Cervantes depuis 2017, le programme Tribuna del Hispanismo s&rsquo;est jusqu&rsquo;\u00e0 pr\u00e9sent pench\u00e9 sur l&rsquo;hispanisme britannique, fran\u00e7ais, italien, jud\u00e9o-espagnol, polonais, portugais, allemand, marocain, irlandais, s\u00e9n\u00e9galais, n\u00e9erlandais, russe, tha\u00eflandais et canadien. L&rsquo;Equatoguin\u00e9en, quant \u00e0 lui, est la quinzi\u00e8me \u00e9dition, et peut \u00eatre vu sur la cha\u00eene YouTube de l&rsquo;Institut Cervantes.<\/p>\n<p>Apr\u00e8s le forum, le directeur de l&rsquo;Instituto Cervantes et le directeur acad\u00e9mique de Cervantes participeront \u00e0 une session de l&rsquo;Acad\u00e9mie \u00e9quatoguin\u00e9enne de la langue espagnole et rencontreront son pr\u00e9sident.<\/p>\n<p>Il y aura \u00e9galement une conf\u00e9rence intitul\u00e9e \u00ab\u00a0L&rsquo;avenir de l&rsquo;espagnol dans le monde\u00a0\u00bb donn\u00e9e par le directeur Garc\u00eda Montero au Centre culturel \u00e9quatoguin\u00e9en, dans laquelle il parlera des priorit\u00e9s de l&rsquo;institution, notamment de l&rsquo;accent mis sur l&rsquo;Afrique subsaharienne, une zone strat\u00e9gique cl\u00e9 pour les missions acad\u00e9miques en raison de sa croissance d\u00e9mographique et \u00e9conomique, avec le lancement du Centre de Dakar (S\u00e9n\u00e9gal) et de l&rsquo;Aula Cervantes d&rsquo;Abidjan (C\u00f4te d&rsquo;Ivoire), ainsi que du futur Observatoire de l&rsquo;espagnol pour l&rsquo;Afrique subsaharienne.<\/p>\n<p>La jeune litt\u00e9rature \u00e9quatoguin\u00e9enne<br \/>\nCe vendredi, le directeur participera \u00e9galement \u00e0 une rencontre avec des \u00e9crivains \u00e9quatoguin\u00e9ens, Estanislao Medina Huesca (1990), laur\u00e9at du prix litt\u00e9raire Miguel de Cervantes de l&rsquo;AEGLE (2017) et premier Africain \u00e0 \u00eatre inclus par le magazine Granta dans sa liste des 25 meilleurs \u00e9crivains de langue espagnole de moins de 35 ans ; Trifonia Melibea Obono Ntutumu (1982), \u00e9crivaine, enseignante et chercheuse sur les questions de femmes et de genre en Afrique ; Juliana Mbengono El\u00e1 Avomo (1996), \u00e9crivaine et journaliste culturelle, laur\u00e9ate du prix Amadou Ndoye de la nouvelle ; Leoncio M\u00e1rquez Merino (1995), po\u00e8te r\u00e9compens\u00e9 par le prix 12 de Octubre D\u00eda de la Hispanidad (2019) ; Teresa Casandra Abeng Esono Nchama (1999), finaliste du prix narratif Miguel de Cervantes organis\u00e9 par AEGLE (2020) ; et Isabel Mikue Rope (1987), \u00e9crivaine d&rsquo;\u0153uvres sociales et directrice d&rsquo;une ONG qui d\u00e9veloppe des programmes pour enfants.<\/p>\n<p>Le prochain legs de Donato Ndongo \u00e0 La Caja de las Letras<br \/>\nSigne de l&rsquo;engagement de l&rsquo;institution \u00e0 faire conna\u00eetre la litt\u00e9rature \u00e9quatoguin\u00e9enne en espagnol, mardi 26 juillet prochain (\u00e0 12h), La Caja de las Letras del Cervantes recevra le legs de l&rsquo;\u00e9crivain Donato Ndongo-Bidyogo (Niefang, Guin\u00e9e \u00e9quatoriale, 1950), figure majeure de la litt\u00e9rature africaine en espagnol et nomm\u00e9 &#8211; dans le cadre d&rsquo;une candidature pr\u00e9sent\u00e9e par Casa \u00c1frica &#8211; pour le Prix Princesse des Asturies des Arts en 2022.<\/p>\n<p>Une table ronde ult\u00e9rieure r\u00e9unira, outre le laur\u00e9at lui-m\u00eame, le directeur de Casa \u00c1frica, Jos\u00e9 Segura Clavell, le professeur Mbuyi Kabunda Badi, sp\u00e9cialis\u00e9 dans les probl\u00e8mes d&rsquo;int\u00e9gration r\u00e9gionale, de d\u00e9veloppement, de genre et de droits de l&rsquo;homme, et l&rsquo;\u00e9crivain Gloria Nistal, sp\u00e9cialiste de la litt\u00e9rature africaine et membre de l&rsquo;Association espagnole des africanistes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luis Garc\u00eda Montero et le pr\u00e9sident de l&rsquo;Acad\u00e9mie \u00e9quatoguin\u00e9enne de la Langue Espagnole ont inaugur\u00e9 la Tribune de l&rsquo;Hispanisme Equatoguin\u00e9en \u00e0 Malabo<\/p>\n","protected":false},"author":12963,"featured_media":12396,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67,53],"tags":[81,78,87],"class_list":{"0":"post-12399","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualites","8":"category-culture-fr","9":"tag-actualites","10":"tag-apie-project-2","11":"tag-culture-2"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;Institut Cervantes \u00e9tudie l&#039;ouverture d&#039;un Observatoire espagnol pour l&#039;Afrique subsaharienne en Guin\u00e9e \u00e9quatoriale - APIE NEWS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Institut Cervantes \u00e9tudie l&#039;ouverture d&#039;un Observatoire espagnol pour l&#039;Afrique subsaharienne en Guin\u00e9e \u00e9quatoriale - APIE NEWS\" \/>\n<meta property=\"og:description\" content=\"Luis Garc\u00eda Montero et le pr\u00e9sident de l&#039;Acad\u00e9mie \u00e9quatoguin\u00e9enne de la Langue Espagnole ont inaugur\u00e9 la Tribune de l&#039;Hispanisme Equatoguin\u00e9en \u00e0 Malabo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/\" \/>\n<meta property=\"og:site_name\" content=\"APIE NEWS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/apieproject\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-24T05:02:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-24T05:02:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/luis-garcia-montero-instituto-cervantes-3_2-684d3b368d0ce2048247ab700530f21d.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"813\" \/>\n\t<meta property=\"og:image:height\" content=\"558\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@apieproject\" \/>\n<meta name=\"twitter:site\" content=\"@apieproject\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/\"},\"author\":{\"name\":\"staff\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/399517cac378948cd7b39086f9ddc2a7\"},\"headline\":\"L&rsquo;Institut Cervantes \u00e9tudie l&rsquo;ouverture d&rsquo;un Observatoire espagnol pour l&rsquo;Afrique subsaharienne en Guin\u00e9e \u00e9quatoriale\",\"datePublished\":\"2022-07-24T05:02:42+00:00\",\"dateModified\":\"2022-07-24T05:02:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/\"},\"wordCount\":1272,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#organization\"},\"image\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/luis-garcia-montero-instituto-cervantes-3_2-684d3b368d0ce2048247ab700530f21d.jpg\",\"keywords\":[\"actualites\",\"apie project\",\"culture\"],\"articleSection\":[\"Actualit\u00e9s\",\"Culture\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/\",\"name\":\"L'Institut Cervantes \u00e9tudie l'ouverture d'un Observatoire espagnol pour l'Afrique subsaharienne en Guin\u00e9e \u00e9quatoriale - APIE NEWS\",\"isPartOf\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/luis-garcia-montero-instituto-cervantes-3_2-684d3b368d0ce2048247ab700530f21d.jpg\",\"datePublished\":\"2022-07-24T05:02:42+00:00\",\"dateModified\":\"2022-07-24T05:02:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#primaryimage\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/luis-garcia-montero-instituto-cervantes-3_2-684d3b368d0ce2048247ab700530f21d.jpg\",\"contentUrl\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/luis-garcia-montero-instituto-cervantes-3_2-684d3b368d0ce2048247ab700530f21d.jpg\",\"width\":813,\"height\":558},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Institut Cervantes \u00e9tudie l&#8217;ouverture d&#8217;un Observatoire espagnol pour l&#8217;Afrique subsaharienne en Guin\u00e9e \u00e9quatoriale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#website\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/\",\"name\":\"APIE NEWS\",\"description\":\"PANAFRICANISM NEWS PORTAL\",\"publisher\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/appsaf.apieproject.com\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#organization\",\"name\":\"APIE PROJECT\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/logo-R-TransparentBackground.png\",\"contentUrl\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/logo-R-TransparentBackground.png\",\"width\":512,\"height\":512,\"caption\":\"APIE PROJECT\"},\"image\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/apieproject\",\"https:\/\/x.com\/apieproject\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/399517cac378948cd7b39086f9ddc2a7\",\"name\":\"staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5386283c5db150efe261184bd59f072a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5386283c5db150efe261184bd59f072a?s=96&d=mm&r=g\",\"caption\":\"staff\"},\"url\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/author\/staff\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Institut Cervantes \u00e9tudie l'ouverture d'un Observatoire espagnol pour l'Afrique subsaharienne en Guin\u00e9e \u00e9quatoriale - APIE NEWS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/","og_locale":"fr_FR","og_type":"article","og_title":"L'Institut Cervantes \u00e9tudie l'ouverture d'un Observatoire espagnol pour l'Afrique subsaharienne en Guin\u00e9e \u00e9quatoriale - APIE NEWS","og_description":"Luis Garc\u00eda Montero et le pr\u00e9sident de l'Acad\u00e9mie \u00e9quatoguin\u00e9enne de la Langue Espagnole ont inaugur\u00e9 la Tribune de l'Hispanisme Equatoguin\u00e9en \u00e0 Malabo","og_url":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/","og_site_name":"APIE NEWS","article_publisher":"https:\/\/facebook.com\/apieproject","article_published_time":"2022-07-24T05:02:42+00:00","article_modified_time":"2022-07-24T05:02:43+00:00","og_image":[{"width":813,"height":558,"url":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/luis-garcia-montero-instituto-cervantes-3_2-684d3b368d0ce2048247ab700530f21d.jpg","type":"image\/jpeg"}],"author":"staff","twitter_card":"summary_large_image","twitter_creator":"@apieproject","twitter_site":"@apieproject","twitter_misc":{"\u00c9crit par":"staff","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#article","isPartOf":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/"},"author":{"name":"staff","@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/399517cac378948cd7b39086f9ddc2a7"},"headline":"L&rsquo;Institut Cervantes \u00e9tudie l&rsquo;ouverture d&rsquo;un Observatoire espagnol pour l&rsquo;Afrique subsaharienne en Guin\u00e9e \u00e9quatoriale","datePublished":"2022-07-24T05:02:42+00:00","dateModified":"2022-07-24T05:02:43+00:00","mainEntityOfPage":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/"},"wordCount":1272,"commentCount":0,"publisher":{"@id":"https:\/\/appsaf.apieproject.com\/news\/#organization"},"image":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#primaryimage"},"thumbnailUrl":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/luis-garcia-montero-instituto-cervantes-3_2-684d3b368d0ce2048247ab700530f21d.jpg","keywords":["actualites","apie project","culture"],"articleSection":["Actualit\u00e9s","Culture"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/","url":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/","name":"L'Institut Cervantes \u00e9tudie l'ouverture d'un Observatoire espagnol pour l'Afrique subsaharienne en Guin\u00e9e \u00e9quatoriale - APIE NEWS","isPartOf":{"@id":"https:\/\/appsaf.apieproject.com\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#primaryimage"},"image":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#primaryimage"},"thumbnailUrl":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/luis-garcia-montero-instituto-cervantes-3_2-684d3b368d0ce2048247ab700530f21d.jpg","datePublished":"2022-07-24T05:02:42+00:00","dateModified":"2022-07-24T05:02:43+00:00","breadcrumb":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#primaryimage","url":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/luis-garcia-montero-instituto-cervantes-3_2-684d3b368d0ce2048247ab700530f21d.jpg","contentUrl":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/luis-garcia-montero-instituto-cervantes-3_2-684d3b368d0ce2048247ab700530f21d.jpg","width":813,"height":558},{"@type":"BreadcrumbList","@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/07\/24\/linstitut-cervantes-etudie-louverture-dun-observatoire-espagnol-pour-lafrique-subsaharienne-en-guinee-equatoriale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/appsaf.apieproject.com\/news\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Institut Cervantes \u00e9tudie l&#8217;ouverture d&#8217;un Observatoire espagnol pour l&#8217;Afrique subsaharienne en Guin\u00e9e \u00e9quatoriale"}]},{"@type":"WebSite","@id":"https:\/\/appsaf.apieproject.com\/news\/#website","url":"https:\/\/appsaf.apieproject.com\/news\/","name":"APIE NEWS","description":"PANAFRICANISM NEWS PORTAL","publisher":{"@id":"https:\/\/appsaf.apieproject.com\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/appsaf.apieproject.com\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/appsaf.apieproject.com\/news\/#organization","name":"APIE PROJECT","url":"https:\/\/appsaf.apieproject.com\/news\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/logo\/image\/","url":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/logo-R-TransparentBackground.png","contentUrl":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/logo-R-TransparentBackground.png","width":512,"height":512,"caption":"APIE PROJECT"},"image":{"@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/apieproject","https:\/\/x.com\/apieproject"]},{"@type":"Person","@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/399517cac378948cd7b39086f9ddc2a7","name":"staff","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5386283c5db150efe261184bd59f072a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5386283c5db150efe261184bd59f072a?s=96&d=mm&r=g","caption":"staff"},"url":"https:\/\/appsaf.apieproject.com\/news\/fr\/author\/staff\/"}]}},"_links":{"self":[{"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/posts\/12399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/users\/12963"}],"replies":[{"embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/comments?post=12399"}],"version-history":[{"count":1,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/posts\/12399\/revisions"}],"predecessor-version":[{"id":12603,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/posts\/12399\/revisions\/12603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/media\/12396"}],"wp:attachment":[{"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/media?parent=12399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/categories?post=12399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/tags?post=12399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}