{"id":19891,"date":"2022-10-13T08:09:33","date_gmt":"2022-10-13T08:09:33","guid":{"rendered":"https:\/\/appsaf.apieproject.com\/news\/?p=19891"},"modified":"2022-10-13T08:09:34","modified_gmt":"2022-10-13T08:09:34","slug":"un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria","status":"publish","type":"post","link":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/","title":{"rendered":"Un Mus\u00e9e De Washington Restitue 29 \u0152uvres D&rsquo;Art Au Nigeria"},"content":{"rendered":"<p>Depuis plusieurs mois, des photographies recouvrent un pan de mur du Mus\u00e9e d&rsquo;art africain \u00e0 Washington. A c\u00f4t\u00e9, d&rsquo;autres photographies montrent les m\u00eames objets d&rsquo;art : des statues de bronze originaires du royaume du Benin, l&rsquo;actuel \u00c9tat de Edo, au Nigeria.<\/p>\n<p>La Sud-Africaine Ngaire Blankenberg, la nouvelle directrice du mus\u00e9e, s&rsquo;est dite \u00ab\u00a0mal \u00e0 l&rsquo;aise\u00a0\u00bb \u00e0 l&rsquo;id\u00e9e d&rsquo;exposer des objets issus de pillages. D\u00e8s son arriv\u00e9e, elle demande \u00e0 son \u00e9quipe de retirer les pi\u00e8ces et de les remplace par des panneaux explicatifs le temps de trouver autre chose \u00e0 exposer. Nous sommes en avril.<\/p>\n<p>Apr\u00e8s de longs mois de discussions, c&rsquo;est maintenant fait. Ce mardi 11 octobre, ce mus\u00e9e qui fait partie du Smithsonian, un massif complexe \u00e9ducatif et culturel situ\u00e9 dans la capitale am\u00e9ricaine, a annonc\u00e9 avoir remis 29 objets d&rsquo;art en bronze aux autorit\u00e9s nig\u00e9rianes. La restitution a \u00e9t\u00e9 officialis\u00e9e lors d&rsquo;une c\u00e9r\u00e9monie \u00e0 laquelle ont pris part Lai Mohammed, ministre de l&rsquo;Information et de la Culture du Nigeria, le prince Aghatise Erediauwa, repr\u00e9sentant l&rsquo;oba, ou souverain, du royaume du Benin, Mme Blankenberg, ainsi que des repr\u00e9sentants de la Galerie nationale d&rsquo;art.<\/p>\n<p>\u00ab\u00a0Non seulement rendre la propri\u00e9t\u00e9 de ces magnifiques artefacts \u00e0 leur domicile l\u00e9gitime \u00e9tait la bonne chose \u00e0 faire, mais cela montre aussi comment nous b\u00e9n\u00e9ficions tous quand les institutions culturelles font des choix \u00e9thiques\u00a0\u00bb, a d\u00e9clar\u00e9 dans un communiqu\u00e9 Lonnie Bunch, le patron du Smithsonian.<\/p>\n<p>Du c\u00f4t\u00e9 des autorit\u00e9s nig\u00e9rianes, on affiche un sentiment de satisfaction. \u200b\u00a0\u00bbLe Nigeria est extr\u00eamement satisfait de la d\u00e9cision louable du Smithsonian&rsquo;s National Museum of African Art, de la National Gallery of Art et de la Rhode Island School of Design de restituer ces objets qui ont quitt\u00e9 l&rsquo;Afrique il y a plus d&rsquo;un si\u00e8cle\u00a0\u00bb, a d\u00e9clar\u00e9 Lai Mohammed.<\/p>\n<p>\u00ab\u00a0En restituant les artefacts, ces institutions \u00e9crivent ensemble de nouvelles pages de l&rsquo;histoire. Leur d\u00e9cision courageuse de restituer les \u0153uvres d&rsquo;art intemporelles m\u00e9rite d&rsquo;\u00eatre imit\u00e9e\u00a0\u00bb, a ajout\u00e9 le ministre.<\/p>\n<p>L&rsquo;initiative d&rsquo;une femme<br \/>\n\u00ab\u00a0Je voulais retirer les oeuvres de Benin City car \u00e7a me blesse. Quand les gens de la diaspora vont dans les mus\u00e9es, ils voient des objets qui ne devraient pas \u00eatre l\u00e0\u00a0\u00bb, explique Mme Blankenberg \u00e0 VOA Afrique, ajoutant que \u00ab\u00a0c\u2019est une sorte de violence, et \u00e7a fait du mal physiquement et mentalement\u00a0\u00bb.<\/p>\n<p>Pour commencer la longue proc\u00e9dure de restitution, Ngaire Blankenberg a contact\u00e9 Abba Isa Tijani, le pr\u00e9sident de la Commission des mus\u00e9es et des monuments du Nigeria pour faire avancer la proc\u00e9dure de restitution. Le mus\u00e9e du Smithsonian \u00e9tant une institution du gouvernement f\u00e9d\u00e9ral am\u00e9ricain, la nouvelle directrice a d\u00fb faire adopter une nouvelle politique pour autoriser le retour des objets d&rsquo;art au Nigeria.<\/p>\n<p>La restitution act\u00e9e mardi est la toute premi\u00e8re du genre, car jusqu&rsquo;ici aucune entit\u00e9 du Smithsonian n&rsquo;avait entrepris de renvoyer en Afrique un quelconque objet d&rsquo;art pill\u00e9 durant l&rsquo;\u00e9poque coloniale. Il aura donc fallu l&rsquo;intervention de Ngaire Blankenberg pour faire bouger les choses dans cette institution vieille de 176 ans.<\/p>\n<p>\u00ab\u00a0Si je veux cr\u00e9er un espace pour les Africains et leurs descendants, et pas seulement les Europ\u00e9ens, c\u2019est important que les objets qui ne devraient pas \u00eatre l\u00e0 n&rsquo;y soient pas\u00a0\u00bb, souligne-t-elle.<\/p>\n<p>Que pense-t-elle des mus\u00e9es europ\u00e9ens qui s&rsquo;opposent \u00e0 la restitution? \u201cIl y a beaucoup d\u2019excuses pour ne pas retourner des objets, et une des excuses est que les mus\u00e9es africains ne sont pas pr\u00eats pour les recevoir, mais ce n\u2019est pas \u00e0 nous de juger\u201d, estime-t-elle. \u201cLa grande question, c\u2019est qui d\u00e9cide des conditions? Pour nous, c\u2019est tr\u00e8s commun dans les mus\u00e9es en Occident de d\u00e9cider de la mani\u00e8re dont on devrait exposer ces objets. En r\u00e9alit\u00e9, ce n\u2019est pas \u00e0 nous de d\u00e9cider\u00a0\u00bb, dit-elle.<\/p>\n<p>Au del\u00e0 de la question de la restitution, c&rsquo;est le soft power des mus\u00e9es qui est en jeu selon elle.<\/p>\n<p>\u201cC\u2019est tr\u00e8s important pour notre strat\u00e9gie: il faut abandonner les contraintes coloniales pour arriver \u00e0 une relation d\u2019\u00e9gal \u00e0 \u00e9gal, mais nous ne pouvons pas faire cela tant qu\u2019on a des objets qui ne sont pas \u00e0 nous\u201d, conclut-elle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La restitution a \u00e9t\u00e9 officialis\u00e9e lors d&rsquo;une c\u00e9r\u00e9monie \u00e0 laquelle a pris part Lai Mohammed, ministre de l&rsquo;Information et de la Culture du Nigeria, qui s&rsquo;est dit \u00ab\u00a0extr\u00eamement satisfait\u00a0\u00bb.<\/p>\n","protected":false},"author":12963,"featured_media":19888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67,53],"tags":[81,78,87],"class_list":{"0":"post-19891","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualites","8":"category-culture-fr","9":"tag-actualites","10":"tag-apie-project-2","11":"tag-culture-2"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un Mus\u00e9e De Washington Restitue 29 \u0152uvres D&#039;Art Au Nigeria - APIE NEWS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un Mus\u00e9e De Washington Restitue 29 \u0152uvres D&#039;Art Au Nigeria - APIE NEWS\" \/>\n<meta property=\"og:description\" content=\"La restitution a \u00e9t\u00e9 officialis\u00e9e lors d&#039;une c\u00e9r\u00e9monie \u00e0 laquelle a pris part Lai Mohammed, ministre de l&#039;Information et de la Culture du Nigeria, qui s&#039;est dit &quot;extr\u00eamement satisfait&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/\" \/>\n<meta property=\"og:site_name\" content=\"APIE NEWS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/apieproject\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-13T08:09:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-13T08:09:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/10\/musee-258356d21657178d225908b2fe3695c9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"651\" \/>\n\t<meta property=\"og:image:height\" content=\"435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@apieproject\" \/>\n<meta name=\"twitter:site\" content=\"@apieproject\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/\"},\"author\":{\"name\":\"staff\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/399517cac378948cd7b39086f9ddc2a7\"},\"headline\":\"Un Mus\u00e9e De Washington Restitue 29 \u0152uvres D&rsquo;Art Au Nigeria\",\"datePublished\":\"2022-10-13T08:09:33+00:00\",\"dateModified\":\"2022-10-13T08:09:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/\"},\"wordCount\":757,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#organization\"},\"image\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/10\/musee-258356d21657178d225908b2fe3695c9.jpg\",\"keywords\":[\"actualites\",\"apie project\",\"culture\"],\"articleSection\":[\"Actualit\u00e9s\",\"Culture\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/\",\"name\":\"Un Mus\u00e9e De Washington Restitue 29 \u0152uvres D'Art Au Nigeria - APIE NEWS\",\"isPartOf\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/10\/musee-258356d21657178d225908b2fe3695c9.jpg\",\"datePublished\":\"2022-10-13T08:09:33+00:00\",\"dateModified\":\"2022-10-13T08:09:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#primaryimage\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/10\/musee-258356d21657178d225908b2fe3695c9.jpg\",\"contentUrl\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/10\/musee-258356d21657178d225908b2fe3695c9.jpg\",\"width\":651,\"height\":435},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un Mus\u00e9e De Washington Restitue 29 \u0152uvres D&#8217;Art Au Nigeria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#website\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/\",\"name\":\"APIE NEWS\",\"description\":\"PANAFRICANISM NEWS PORTAL\",\"publisher\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/appsaf.apieproject.com\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#organization\",\"name\":\"APIE PROJECT\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/logo-R-TransparentBackground.png\",\"contentUrl\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/logo-R-TransparentBackground.png\",\"width\":512,\"height\":512,\"caption\":\"APIE PROJECT\"},\"image\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/apieproject\",\"https:\/\/x.com\/apieproject\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/399517cac378948cd7b39086f9ddc2a7\",\"name\":\"staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5386283c5db150efe261184bd59f072a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5386283c5db150efe261184bd59f072a?s=96&d=mm&r=g\",\"caption\":\"staff\"},\"url\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/author\/staff\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un Mus\u00e9e De Washington Restitue 29 \u0152uvres D'Art Au Nigeria - APIE NEWS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/","og_locale":"fr_FR","og_type":"article","og_title":"Un Mus\u00e9e De Washington Restitue 29 \u0152uvres D'Art Au Nigeria - APIE NEWS","og_description":"La restitution a \u00e9t\u00e9 officialis\u00e9e lors d'une c\u00e9r\u00e9monie \u00e0 laquelle a pris part Lai Mohammed, ministre de l'Information et de la Culture du Nigeria, qui s'est dit \"extr\u00eamement satisfait\".","og_url":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/","og_site_name":"APIE NEWS","article_publisher":"https:\/\/facebook.com\/apieproject","article_published_time":"2022-10-13T08:09:33+00:00","article_modified_time":"2022-10-13T08:09:34+00:00","og_image":[{"width":651,"height":435,"url":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/10\/musee-258356d21657178d225908b2fe3695c9.jpg","type":"image\/jpeg"}],"author":"staff","twitter_card":"summary_large_image","twitter_creator":"@apieproject","twitter_site":"@apieproject","twitter_misc":{"\u00c9crit par":"staff","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#article","isPartOf":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/"},"author":{"name":"staff","@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/399517cac378948cd7b39086f9ddc2a7"},"headline":"Un Mus\u00e9e De Washington Restitue 29 \u0152uvres D&rsquo;Art Au Nigeria","datePublished":"2022-10-13T08:09:33+00:00","dateModified":"2022-10-13T08:09:34+00:00","mainEntityOfPage":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/"},"wordCount":757,"commentCount":0,"publisher":{"@id":"https:\/\/appsaf.apieproject.com\/news\/#organization"},"image":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#primaryimage"},"thumbnailUrl":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/10\/musee-258356d21657178d225908b2fe3695c9.jpg","keywords":["actualites","apie project","culture"],"articleSection":["Actualit\u00e9s","Culture"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/","url":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/","name":"Un Mus\u00e9e De Washington Restitue 29 \u0152uvres D'Art Au Nigeria - APIE NEWS","isPartOf":{"@id":"https:\/\/appsaf.apieproject.com\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#primaryimage"},"image":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#primaryimage"},"thumbnailUrl":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/10\/musee-258356d21657178d225908b2fe3695c9.jpg","datePublished":"2022-10-13T08:09:33+00:00","dateModified":"2022-10-13T08:09:34+00:00","breadcrumb":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#primaryimage","url":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/10\/musee-258356d21657178d225908b2fe3695c9.jpg","contentUrl":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/10\/musee-258356d21657178d225908b2fe3695c9.jpg","width":651,"height":435},{"@type":"BreadcrumbList","@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/10\/13\/un-musee-de-washington-restitue-29-oeuvres-dart-au-nigeria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/appsaf.apieproject.com\/news\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Un Mus\u00e9e De Washington Restitue 29 \u0152uvres D&#8217;Art Au Nigeria"}]},{"@type":"WebSite","@id":"https:\/\/appsaf.apieproject.com\/news\/#website","url":"https:\/\/appsaf.apieproject.com\/news\/","name":"APIE NEWS","description":"PANAFRICANISM NEWS PORTAL","publisher":{"@id":"https:\/\/appsaf.apieproject.com\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/appsaf.apieproject.com\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/appsaf.apieproject.com\/news\/#organization","name":"APIE PROJECT","url":"https:\/\/appsaf.apieproject.com\/news\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/logo\/image\/","url":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/logo-R-TransparentBackground.png","contentUrl":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/logo-R-TransparentBackground.png","width":512,"height":512,"caption":"APIE PROJECT"},"image":{"@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/apieproject","https:\/\/x.com\/apieproject"]},{"@type":"Person","@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/399517cac378948cd7b39086f9ddc2a7","name":"staff","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5386283c5db150efe261184bd59f072a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5386283c5db150efe261184bd59f072a?s=96&d=mm&r=g","caption":"staff"},"url":"https:\/\/appsaf.apieproject.com\/news\/fr\/author\/staff\/"}]}},"_links":{"self":[{"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/posts\/19891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/users\/12963"}],"replies":[{"embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/comments?post=19891"}],"version-history":[{"count":1,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/posts\/19891\/revisions"}],"predecessor-version":[{"id":20077,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/posts\/19891\/revisions\/20077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/media\/19888"}],"wp:attachment":[{"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/media?parent=19891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/categories?post=19891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/tags?post=19891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}