{"id":8226,"date":"2022-05-22T23:26:58","date_gmt":"2022-05-22T23:26:58","guid":{"rendered":"https:\/\/appsaf.apieproject.com\/news\/?p=8226"},"modified":"2022-05-22T23:26:59","modified_gmt":"2022-05-22T23:26:59","slug":"lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication","status":"publish","type":"post","link":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/","title":{"rendered":"L&rsquo;Afrique du Sud pr\u00e9pare le lancement de son propre satellite de communication"},"content":{"rendered":"<p>L\u2019Afrique du Sud pourra bient\u00f4t lancer son propre satellite de communication. Khumbudzo Ntshavheni (photo), ministre des Communications et des Technologies num\u00e9riques, a d\u00e9clar\u00e9 le mercredi 18 mai que le projet avance bon train, sans pr\u00e9ciser le calendrier pr\u00e9vu \u00e0 cet effet.<\/p>\n<p>Le satellite permettrait de mettre en place une centrale africaine d\u2019\u00e9change de voix, de donn\u00e9es et d\u2019autres moyens de communication. \u00ab\u2009Pour am\u00e9liorer notre port\u00e9e de connectivit\u00e9 \u00e0 large bande et conform\u00e9ment \u00e0 la d\u00e9cision du Cabinet de 2016, l\u2019Afrique du Sud est maintenant pr\u00eate \u00e0 lancer son propre satellite de communication par l\u2019interm\u00e9diaire de Sentech en partenariat avec l\u2019Agence spatiale nationale et d\u2019autres parties prenantes cl\u00e9s\u2009\u00bb, a d\u00e9clar\u00e9 Mme Ntshavheni lors d\u2019un vote de discours budg\u00e9taire devant une commission parlementaire.<\/p>\n<p>Ce projet s\u2019inscrit dans le cadre du renforcement du programme de satellite sud-africain pour soutenir la quatri\u00e8me r\u00e9volution industrielle. L\u2019\u00e9laboration du programme r\u00e9vis\u00e9 devrait prendre entre huit et dix ans. En 2017, l\u2019ancienne ministre des Communications, Stella Ndabeni-Abrahams, avait d\u00e9clar\u00e9 que son d\u00e9partement \u00e9tudiait la technologie satellitaire comme un moyen possible d\u2019apporter la connectivit\u00e9 Internet \u00e0 tous les Sud-Africains, y compris ceux vivant dans les milieux qui ne sont pas couverts par les r\u00e9seaux terrestres.<\/p>\n<p>Selon Khumbudzo Ntshavheni, la mise en service de ce satellite de communication devrait consacrer la \u00ab\u2009souverainet\u00e9 en mati\u00e8re de technologie et de donn\u00e9es\u2009\u00bb de l\u2019Afrique du Sud. Cela devrait \u00e9galement permettre de r\u00e9duire les co\u00fbts de location de la capacit\u00e9 satellitaire aussi bien pour le gouvernement, que pour les autres secteurs qui d\u00e9pendent des technologies de communication par satellite pour leurs activit\u00e9s. Le pays envisage \u00e9galement de fournir des services \u00e0 l&rsquo;ensemble de la r\u00e9gion de la Communaut\u00e9 de d\u00e9veloppement de l&rsquo;Afrique australe (SADC).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Afrique du Sud ambitionne de devenir un fournisseur de services t\u00e9l\u00e9coms, notamment pour les autres pays du continent. \u00c0 cet effet, le pays multiplie les investissements dans le d\u00e9veloppement d\u2019infrastructures spatiales.<\/p>\n","protected":false},"author":12963,"featured_media":8223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[67,59,73],"tags":[81,78,77],"class_list":{"0":"post-8226","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-actualites","8":"category-speciaux","9":"category-technologie","10":"tag-actualites","11":"tag-apie-project-2","12":"tag-technologie"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;Afrique du Sud pr\u00e9pare le lancement de son propre satellite de communication - APIE NEWS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Afrique du Sud pr\u00e9pare le lancement de son propre satellite de communication - APIE NEWS\" \/>\n<meta property=\"og:description\" content=\"L\u2019Afrique du Sud ambitionne de devenir un fournisseur de services t\u00e9l\u00e9coms, notamment pour les autres pays du continent. \u00c0 cet effet, le pays multiplie les investissements dans le d\u00e9veloppement d\u2019infrastructures spatiales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/\" \/>\n<meta property=\"og:site_name\" content=\"APIE NEWS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/apieproject\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-22T23:26:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-22T23:26:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/05\/1905-97829-lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication_M-e33187a18d588fc64cdb3b2e0e9d7013.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"268\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"staff\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@apieproject\" \/>\n<meta name=\"twitter:site\" content=\"@apieproject\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"staff\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/\"},\"author\":{\"name\":\"staff\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/399517cac378948cd7b39086f9ddc2a7\"},\"headline\":\"L&rsquo;Afrique du Sud pr\u00e9pare le lancement de son propre satellite de communication\",\"datePublished\":\"2022-05-22T23:26:58+00:00\",\"dateModified\":\"2022-05-22T23:26:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/\"},\"wordCount\":329,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#organization\"},\"image\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/05\/1905-97829-lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication_M-e33187a18d588fc64cdb3b2e0e9d7013.jpg\",\"keywords\":[\"actualites\",\"apie project\",\"technologie\"],\"articleSection\":[\"Actualit\u00e9s\",\"Sp\u00e9ciaux\",\"Technologie\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/\",\"name\":\"L'Afrique du Sud pr\u00e9pare le lancement de son propre satellite de communication - APIE NEWS\",\"isPartOf\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/05\/1905-97829-lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication_M-e33187a18d588fc64cdb3b2e0e9d7013.jpg\",\"datePublished\":\"2022-05-22T23:26:58+00:00\",\"dateModified\":\"2022-05-22T23:26:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#primaryimage\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/05\/1905-97829-lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication_M-e33187a18d588fc64cdb3b2e0e9d7013.jpg\",\"contentUrl\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/05\/1905-97829-lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication_M-e33187a18d588fc64cdb3b2e0e9d7013.jpg\",\"width\":450,\"height\":268},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Afrique du Sud pr\u00e9pare le lancement de son propre satellite de communication\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#website\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/\",\"name\":\"APIE NEWS\",\"description\":\"PANAFRICANISM NEWS PORTAL\",\"publisher\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/appsaf.apieproject.com\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#organization\",\"name\":\"APIE PROJECT\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/logo-R-TransparentBackground.png\",\"contentUrl\":\"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/logo-R-TransparentBackground.png\",\"width\":512,\"height\":512,\"caption\":\"APIE PROJECT\"},\"image\":{\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/facebook.com\/apieproject\",\"https:\/\/x.com\/apieproject\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/399517cac378948cd7b39086f9ddc2a7\",\"name\":\"staff\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5386283c5db150efe261184bd59f072a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5386283c5db150efe261184bd59f072a?s=96&d=mm&r=g\",\"caption\":\"staff\"},\"url\":\"https:\/\/appsaf.apieproject.com\/news\/fr\/author\/staff\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Afrique du Sud pr\u00e9pare le lancement de son propre satellite de communication - APIE NEWS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/","og_locale":"fr_FR","og_type":"article","og_title":"L'Afrique du Sud pr\u00e9pare le lancement de son propre satellite de communication - APIE NEWS","og_description":"L\u2019Afrique du Sud ambitionne de devenir un fournisseur de services t\u00e9l\u00e9coms, notamment pour les autres pays du continent. \u00c0 cet effet, le pays multiplie les investissements dans le d\u00e9veloppement d\u2019infrastructures spatiales.","og_url":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/","og_site_name":"APIE NEWS","article_publisher":"https:\/\/facebook.com\/apieproject","article_published_time":"2022-05-22T23:26:58+00:00","article_modified_time":"2022-05-22T23:26:59+00:00","og_image":[{"width":450,"height":268,"url":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/05\/1905-97829-lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication_M-e33187a18d588fc64cdb3b2e0e9d7013.jpg","type":"image\/jpeg"}],"author":"staff","twitter_card":"summary_large_image","twitter_creator":"@apieproject","twitter_site":"@apieproject","twitter_misc":{"\u00c9crit par":"staff","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#article","isPartOf":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/"},"author":{"name":"staff","@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/399517cac378948cd7b39086f9ddc2a7"},"headline":"L&rsquo;Afrique du Sud pr\u00e9pare le lancement de son propre satellite de communication","datePublished":"2022-05-22T23:26:58+00:00","dateModified":"2022-05-22T23:26:59+00:00","mainEntityOfPage":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/"},"wordCount":329,"commentCount":0,"publisher":{"@id":"https:\/\/appsaf.apieproject.com\/news\/#organization"},"image":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#primaryimage"},"thumbnailUrl":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/05\/1905-97829-lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication_M-e33187a18d588fc64cdb3b2e0e9d7013.jpg","keywords":["actualites","apie project","technologie"],"articleSection":["Actualit\u00e9s","Sp\u00e9ciaux","Technologie"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/","url":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/","name":"L'Afrique du Sud pr\u00e9pare le lancement de son propre satellite de communication - APIE NEWS","isPartOf":{"@id":"https:\/\/appsaf.apieproject.com\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#primaryimage"},"image":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#primaryimage"},"thumbnailUrl":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/05\/1905-97829-lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication_M-e33187a18d588fc64cdb3b2e0e9d7013.jpg","datePublished":"2022-05-22T23:26:58+00:00","dateModified":"2022-05-22T23:26:59+00:00","breadcrumb":{"@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#primaryimage","url":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/05\/1905-97829-lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication_M-e33187a18d588fc64cdb3b2e0e9d7013.jpg","contentUrl":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/05\/1905-97829-lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication_M-e33187a18d588fc64cdb3b2e0e9d7013.jpg","width":450,"height":268},{"@type":"BreadcrumbList","@id":"https:\/\/appsaf.apieproject.com\/news\/fr\/2022\/05\/22\/lafrique-du-sud-prepare-le-lancement-de-son-propre-satellite-de-communication\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/appsaf.apieproject.com\/news\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Afrique du Sud pr\u00e9pare le lancement de son propre satellite de communication"}]},{"@type":"WebSite","@id":"https:\/\/appsaf.apieproject.com\/news\/#website","url":"https:\/\/appsaf.apieproject.com\/news\/","name":"APIE NEWS","description":"PANAFRICANISM NEWS PORTAL","publisher":{"@id":"https:\/\/appsaf.apieproject.com\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/appsaf.apieproject.com\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/appsaf.apieproject.com\/news\/#organization","name":"APIE PROJECT","url":"https:\/\/appsaf.apieproject.com\/news\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/logo\/image\/","url":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/logo-R-TransparentBackground.png","contentUrl":"https:\/\/appsaf.apieproject.com\/news\/wp-content\/uploads\/sites\/29\/2022\/07\/logo-R-TransparentBackground.png","width":512,"height":512,"caption":"APIE PROJECT"},"image":{"@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/apieproject","https:\/\/x.com\/apieproject"]},{"@type":"Person","@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/399517cac378948cd7b39086f9ddc2a7","name":"staff","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/appsaf.apieproject.com\/news\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5386283c5db150efe261184bd59f072a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5386283c5db150efe261184bd59f072a?s=96&d=mm&r=g","caption":"staff"},"url":"https:\/\/appsaf.apieproject.com\/news\/fr\/author\/staff\/"}]}},"_links":{"self":[{"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/posts\/8226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/users\/12963"}],"replies":[{"embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/comments?post=8226"}],"version-history":[{"count":1,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/posts\/8226\/revisions"}],"predecessor-version":[{"id":8474,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/posts\/8226\/revisions\/8474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/media\/8223"}],"wp:attachment":[{"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/media?parent=8226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/categories?post=8226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/appsaf.apieproject.com\/news\/fr\/wp-json\/wp\/v2\/tags?post=8226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}